{"id":195320,"date":"2025-07-30T17:06:40","date_gmt":"2025-07-30T17:06:40","guid":{"rendered":"https:\/\/www.avo.it\/ruota\/avo-rad-aus-polyamid-6-mit-halterung-in-stahl-fuer-die-industrie-durchmesser-150mm-ean-28220-2\/"},"modified":"2026-02-13T00:59:18","modified_gmt":"2026-02-13T00:59:18","slug":"avo-rad-aus-polyamid-6-mit-halterung-in-stahl-fuer-die-industrie-durchmesser-150mm-ean-28220-2","status":"publish","type":"ruota","link":"https:\/\/www.avo.it\/de\/rad\/avo-rad-aus-polyamid-6-mit-halterung-in-stahl-fuer-die-industrie-durchmesser-150mm-ean-28220-2\/","title":{"rendered":"AVO &#8211; Rad aus  polyamid 6 mit halterung in stahl f\u00fcr die industrie, durchmesser 150mm ean 28220"},"content":{"rendered":"<p> Verst\u00e4rktes Vollkunststoffrad aus Polyamid 6. Nabe mit glatter Bohrung, ausgestattet mit Rollenlagern oder abgedichteten Pr\u00e4zisions-Rillenkugellagern und Distanzh\u00fclse.<\/p>\n","protected":false},"featured_media":96861,"menu_order":0,"template":"","meta":{"_acf_changed":false},"ambito":[2281],"applicazione":[],"colore":[2286],"finitura-supporto":[2443],"freno":[],"attributo":[2284],"materiale":[2278,2277],"nucleo":[2282],"pavimentazione":[2394,2279],"perno":[],"rotazione":[2283],"serie":[2628],"struttura-supporto":[2412],"tipo-perno":[],"tipo-ruota":[2024],"tipo-supporto":[2457],"versione-mozzo":[2285],"versione-supporto":[],"class_list":["post-195320","ruota","type-ruota","status-publish","has-post-thumbnail","hentry","ambito-industrie-de","colore-weisse","finitura-supporto-schwarz-lackiert","attributo-polyamid","materiale-6-de","materiale-polyamid","nucleo-polyamid-6","pavimentazione-beton","pavimentazione-steigut","rotazione-kugellager","serie-116-ps-de","struttura-supporto-behoben","tipo-ruota-ruota-supporto","tipo-supporto-extra-robuste-doppelstuetze","versione-mozzo-kugellager"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/ruota\/195320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/ruota"}],"about":[{"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/types\/ruota"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/media\/96861"}],"wp:attachment":[{"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/media?parent=195320"}],"wp:term":[{"taxonomy":"ambito","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/ambito?post=195320"},{"taxonomy":"applicazione","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/applicazione?post=195320"},{"taxonomy":"colore","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/colore?post=195320"},{"taxonomy":"finitura-supporto","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/finitura-supporto?post=195320"},{"taxonomy":"freno","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/freno?post=195320"},{"taxonomy":"attributo","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/attributo?post=195320"},{"taxonomy":"materiale","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/materiale?post=195320"},{"taxonomy":"nucleo","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/nucleo?post=195320"},{"taxonomy":"pavimentazione","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/pavimentazione?post=195320"},{"taxonomy":"perno","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/perno?post=195320"},{"taxonomy":"rotazione","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/rotazione?post=195320"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/serie?post=195320"},{"taxonomy":"struttura-supporto","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/struttura-supporto?post=195320"},{"taxonomy":"tipo-perno","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/tipo-perno?post=195320"},{"taxonomy":"tipo-ruota","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/tipo-ruota?post=195320"},{"taxonomy":"tipo-supporto","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/tipo-supporto?post=195320"},{"taxonomy":"versione-mozzo","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/versione-mozzo?post=195320"},{"taxonomy":"versione-supporto","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/versione-supporto?post=195320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}