{"id":205635,"date":"2026-05-12T10:46:13","date_gmt":"2026-05-12T10:46:13","guid":{"rendered":"https:\/\/www.avo.it\/ruota\/avo-rad-aus-gummi-fleckenabweisend-mit-halterung-in-stahl-fuer-die-industrie-durchmesser-306mm-ean-29207\/"},"modified":"2026-05-13T07:47:03","modified_gmt":"2026-05-13T07:47:03","slug":"avo-rad-aus-gummi-fleckenabweisend-mit-halterung-in-stahl-fuer-die-industrie-durchmesser-306mm-ean-29207","status":"publish","type":"ruota","link":"https:\/\/www.avo.it\/de\/rad\/avo-rad-aus-gummi-fleckenabweisend-mit-halterung-in-stahl-fuer-die-industrie-durchmesser-306mm-ean-29207\/","title":{"rendered":"AVO &#8211; Rad aus  gummi fleckenabweisend mit halterung in stahl f\u00fcr die industrie, durchmesser 306mm ean 29207"},"content":{"rendered":"<p> Extrem robustes Elastikrad aus Vollgummi, grau und spurlos, H\u00e4rte 65-70 Shore A, mit Felgen aus gepresstem, verzinkt-chromatiertem Stahl. Sehr hoher Laufkomfort, \u00e4u\u00dferst sto\u00df- und schnittfest sowie vibrationsd\u00e4mpfend. Radk\u00f6rper mit Rillenkugellager 2RS oder Edelstahl-Rillenkugellager 2RS.<\/p>\n","protected":false},"featured_media":205845,"menu_order":0,"template":"","meta":{"_acf_changed":false},"ambito":[2281],"applicazione":[],"colore":[2403],"finitura-supporto":[2443],"freno":[],"attributo":[2396],"materiale":[1833,3350,2391],"nucleo":[2428],"pavimentazione":[2280,2394,2393,2279,2476],"perno":[],"rotazione":[2283],"serie":[3423],"struttura-supporto":[2412],"tipo-perno":[],"tipo-ruota":[2024],"tipo-supporto":[2442],"versione-mozzo":[2285],"versione-supporto":[],"class_list":["post-205635","ruota","type-ruota","status-publish","has-post-thumbnail","hentry","ambito-industrie-de","colore-grau","finitura-supporto-schwarz-lackiert","attributo-gummi","materiale-antimacchia","materiale-fleckenabweisend","materiale-gummi","nucleo-stahl","pavimentazione-asphalt-de","pavimentazione-beton","pavimentazione-gegrillter","pavimentazione-steigut","pavimentazione-unbefestigte-strasse","rotazione-kugellager","serie-604-am-de","struttura-supporto-behoben","tipo-ruota-ruota-supporto","tipo-supporto-extrastarke-unterstuetzung","versione-mozzo-kugellager"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/ruota\/205635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/ruota"}],"about":[{"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/types\/ruota"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/media\/205845"}],"wp:attachment":[{"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/media?parent=205635"}],"wp:term":[{"taxonomy":"ambito","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/ambito?post=205635"},{"taxonomy":"applicazione","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/applicazione?post=205635"},{"taxonomy":"colore","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/colore?post=205635"},{"taxonomy":"finitura-supporto","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/finitura-supporto?post=205635"},{"taxonomy":"freno","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/freno?post=205635"},{"taxonomy":"attributo","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/attributo?post=205635"},{"taxonomy":"materiale","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/materiale?post=205635"},{"taxonomy":"nucleo","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/nucleo?post=205635"},{"taxonomy":"pavimentazione","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/pavimentazione?post=205635"},{"taxonomy":"perno","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/perno?post=205635"},{"taxonomy":"rotazione","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/rotazione?post=205635"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/serie?post=205635"},{"taxonomy":"struttura-supporto","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/struttura-supporto?post=205635"},{"taxonomy":"tipo-perno","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/tipo-perno?post=205635"},{"taxonomy":"tipo-ruota","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/tipo-ruota?post=205635"},{"taxonomy":"tipo-supporto","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/tipo-supporto?post=205635"},{"taxonomy":"versione-mozzo","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/versione-mozzo?post=205635"},{"taxonomy":"versione-supporto","embeddable":true,"href":"https:\/\/www.avo.it\/de\/wp-json\/wp\/v2\/versione-supporto?post=205635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}