{"id":118106,"date":"2025-07-10T07:30:34","date_gmt":"2025-07-10T07:30:34","guid":{"rendered":"https:\/\/avo.dkrweb.it\/ruota\/avo-rueda-de-goma-siliconica-alta-termperatura-con-soporte-acciaio-para-industria-diametro-100mm\/"},"modified":"2026-02-12T21:55:07","modified_gmt":"2026-02-12T21:55:07","slug":"avo-rueda-de-goma-siliconica-alta-termperatura-con-soporte-acciaio-para-industria-diametro-100mm","status":"publish","type":"ruota","link":"https:\/\/www.avo.it\/es\/rueda\/avo-rueda-de-goma-siliconica-alta-termperatura-con-soporte-acciaio-para-industria-diametro-100mm\/","title":{"rendered":"AVO &#8211; Rueda de goma silicona para altas temperatur con soporte de acero para industria, di\u00e1metro 100mm"},"content":{"rendered":"<p> Rueda con banda de rodadura de caucho 80 Shore A para altas temperaturas y discos de acero estampado con recubrimiento cincado-cromado. Buje con rodamientos de bolas de precisi\u00f3n estancos.<\/p>\n","protected":false},"featured_media":89947,"menu_order":0,"template":"","meta":{"_acf_changed":false},"ambito":[118],"applicazione":[],"colore":[2329],"finitura-supporto":[2297],"freno":[],"attributo":[2303],"materiale":[2287,2328],"nucleo":[2324],"pavimentazione":[2271,2270,2290],"perno":[],"rotazione":[2273],"serie":[2609],"struttura-supporto":[2296],"tipo-perno":[],"tipo-ruota":[2024],"tipo-supporto":[2295],"versione-mozzo":[2275],"versione-supporto":[2314],"class_list":["post-118106","ruota","type-ruota","status-publish","has-post-thumbnail","hentry","ambito-industria-es","colore-rojo","finitura-supporto-galvanizado","attributo-altas-temperaturas","materiale-goma","materiale-silicona-para-altas-temperatur","nucleo-de-acero","pavimentazione-asfalto-es","pavimentazione-gres-es","pavimentazione-hormigon","rotazione-cojinete-a-bolas","serie-112a-at-es","struttura-supporto-giratorio","tipo-ruota-ruota-supporto","tipo-supporto-ruedas-para-cargas-medianas","versione-mozzo-cojinete-a-bolas","versione-supporto-agujero-pasante"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/ruota\/118106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/ruota"}],"about":[{"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/types\/ruota"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/media\/89947"}],"wp:attachment":[{"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/media?parent=118106"}],"wp:term":[{"taxonomy":"ambito","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/ambito?post=118106"},{"taxonomy":"applicazione","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/applicazione?post=118106"},{"taxonomy":"colore","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/colore?post=118106"},{"taxonomy":"finitura-supporto","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/finitura-supporto?post=118106"},{"taxonomy":"freno","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/freno?post=118106"},{"taxonomy":"attributo","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/attributo?post=118106"},{"taxonomy":"materiale","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/materiale?post=118106"},{"taxonomy":"nucleo","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/nucleo?post=118106"},{"taxonomy":"pavimentazione","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/pavimentazione?post=118106"},{"taxonomy":"perno","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/perno?post=118106"},{"taxonomy":"rotazione","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/rotazione?post=118106"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/serie?post=118106"},{"taxonomy":"struttura-supporto","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/struttura-supporto?post=118106"},{"taxonomy":"tipo-perno","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/tipo-perno?post=118106"},{"taxonomy":"tipo-ruota","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/tipo-ruota?post=118106"},{"taxonomy":"tipo-supporto","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/tipo-supporto?post=118106"},{"taxonomy":"versione-mozzo","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/versione-mozzo?post=118106"},{"taxonomy":"versione-supporto","embeddable":true,"href":"https:\/\/www.avo.it\/es\/wp-json\/wp\/v2\/versione-supporto?post=118106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}